{"id":6,"count":0,"description":"","link":"https:\/\/dev.smk.agency\/arealibre\/product_cat\/conjuntos\/","name":"Conjuntos","slug":"conjuntos","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.smk.agency\/arealibre\/wp-json\/wp\/v2\/product_cat\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.smk.agency\/arealibre\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dev.smk.agency\/arealibre\/wp-json\/wp\/v2\/taxonomies\/product_cat"}]}}